{"id":99,"count":4,"description":"","link":"https:\/\/www.terhalle.de\/en\/referenz_bereich\/houses\/","name":"Houses","slug":"houses","taxonomy":"referenz_bereich","parent":93,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Houses Archive - Terhalle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.terhalle.de\/en\/referenz_bereich\/houses\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Houses Archive - Terhalle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.terhalle.de\/en\/referenz_bereich\/houses\/\" \/>\n<meta property=\"og:site_name\" content=\"Terhalle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/referenz_bereich\\\/houses\\\/\",\"url\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/referenz_bereich\\\/houses\\\/\",\"name\":\"Houses Archive - Terhalle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/referenz_bereich\\\/houses\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/referenz_bereich\\\/houses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turnkey construction\",\"item\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/referenz_bereich\\\/turnkey-construction\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Houses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/\",\"name\":\"Terhalle\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/#organization\",\"name\":\"Terhalle\",\"url\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.terhalle.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Terhalle_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.terhalle.de\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Terhalle_Logo.svg\",\"width\":100,\"height\":100,\"caption\":\"Terhalle\"},\"image\":{\"@id\":\"https:\\\/\\\/www.terhalle.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Houses Archive - Terhalle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.terhalle.de\/en\/referenz_bereich\/houses\/","og_locale":"en_US","og_type":"article","og_title":"Houses Archive - Terhalle","og_url":"https:\/\/www.terhalle.de\/en\/referenz_bereich\/houses\/","og_site_name":"Terhalle","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.terhalle.de\/en\/referenz_bereich\/houses\/","url":"https:\/\/www.terhalle.de\/en\/referenz_bereich\/houses\/","name":"Houses Archive - Terhalle","isPartOf":{"@id":"https:\/\/www.terhalle.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.terhalle.de\/en\/referenz_bereich\/houses\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.terhalle.de\/en\/referenz_bereich\/houses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.terhalle.de\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Turnkey construction","item":"https:\/\/www.terhalle.de\/en\/referenz_bereich\/turnkey-construction\/"},{"@type":"ListItem","position":3,"name":"Houses"}]},{"@type":"WebSite","@id":"https:\/\/www.terhalle.de\/en\/#website","url":"https:\/\/www.terhalle.de\/en\/","name":"Terhalle","description":"","publisher":{"@id":"https:\/\/www.terhalle.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.terhalle.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.terhalle.de\/en\/#organization","name":"Terhalle","url":"https:\/\/www.terhalle.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.terhalle.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.terhalle.de\/wp-content\/uploads\/2022\/08\/Terhalle_Logo.svg","contentUrl":"https:\/\/www.terhalle.de\/wp-content\/uploads\/2022\/08\/Terhalle_Logo.svg","width":100,"height":100,"caption":"Terhalle"},"image":{"@id":"https:\/\/www.terhalle.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.terhalle.de\/en\/wp-json\/wp\/v2\/referenz_bereich\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.terhalle.de\/en\/wp-json\/wp\/v2\/referenz_bereich"}],"about":[{"href":"https:\/\/www.terhalle.de\/en\/wp-json\/wp\/v2\/taxonomies\/referenz_bereich"}],"up":[{"embeddable":true,"href":"https:\/\/www.terhalle.de\/en\/wp-json\/wp\/v2\/referenz_bereich\/93"}],"wp:post_type":[{"href":"https:\/\/www.terhalle.de\/en\/wp-json\/wp\/v2\/projekte?referenz_bereich=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}